{"id":4678,"date":"2025-08-04T10:52:09","date_gmt":"2025-08-04T14:52:09","guid":{"rendered":"https:\/\/gobierno.udd.cl\/doctorado\/?p=4678"},"modified":"2025-08-05T10:53:00","modified_gmt":"2025-08-05T14:53:00","slug":"doctorado-en-ciencias-de-la-complejidad-social-suma-nuevo-graduado-con-tesis-sobre-oscilaciones-cerebrales-complejas","status":"publish","type":"post","link":"https:\/\/gobierno.udd.cl\/dccs\/2025\/08\/04\/doctorado-en-ciencias-de-la-complejidad-social-suma-nuevo-graduado-con-tesis-sobre-oscilaciones-cerebrales-complejas\/","title":{"rendered":"Doctorado en Ciencias de la Complejidad Social suma nuevo graduado con tesis sobre oscilaciones cerebrales complejas"},"content":{"rendered":"\n<p><em>Con este nuevo graduado, el programa de la Facultad de Gobierno UDD suma un total de 24 doctores que han recibido el grado desde su creaci\u00f3n.<\/em><\/p>\n\n\n\n<p>V\u00edctor M\u00e1rquez defendi\u00f3 con \u00e9xito su tesis titulada <em>\u201cComplex Oscillatory Dynamics in Neural Populations Using Map-Based Models\u201d<\/em>, obteniendo el grado de <strong>Doctor en Ciencias de la Complejidad Social<\/strong>, otorgado por la Universidad del Desarrollo.<\/p>\n\n\n\n<p>La defensa, de car\u00e1cter p\u00fablico, se realiz\u00f3 en el Edificio de Postgrado del campus Rector Ernesto Silva Bafalluy y cont\u00f3 con la presencia de la comunidad acad\u00e9mica, tanto de forma presencial como remota. La comisi\u00f3n evaluadora estuvo integrada por el Dr. Jorge F\u00e1brega, evaluador interno del equipo del Centro de Investigaci\u00f3n en Complejidad Social UDD; y el Dr. Vicente Medel, evaluador externo de la Universidad Adolfo Ib\u00e1\u00f1ez.<\/p>\n\n\n\n<p>V\u00edctor M\u00e1rquez, quien ingres\u00f3 al programa en la cohorte 2018, desarroll\u00f3 una investigaci\u00f3n que combina neurociencia computacional, f\u00edsica te\u00f3rica y ciencia de redes para analizar la din\u00e1mica oscilatoria en poblaciones neuronales, utilizando modelos matem\u00e1ticos basados en mapas. Su trabajo refleja el enfoque interdisciplinario del Doctorado en Ciencias de la Complejidad Social, que busca comprender fen\u00f3menos complejos desde m\u00faltiples perspectivas cient\u00edficas.<\/p>\n\n\n\n<p>Jos\u00e9 Antonio Mu\u00f1oz, director del programa, destac\u00f3 que \u201cseguir sumando doctores a nuestro programa es una se\u00f1al concreta del desarrollo y consolidaci\u00f3n de esta comunidad acad\u00e9mica interdisciplinaria, en un momento especialmente significativo tras recibir siete a\u00f1os de acreditaci\u00f3n. Esto reafirma nuestro compromiso con la excelencia y la formaci\u00f3n avanzada en ciencias de la complejidad.\u201d<\/p>\n\n\n<section class=\"wp-block-udd-gallery-carousel wp-carousel-gallery\">\n\t<div class=\"container\">\n\t\t<div\n\t\t\tclass=\"slick-carousel gallery-slick-carousel gallery-carousel--1\"\n\t\t\tdata-slick='{&quot;slidesToScroll&quot;:1,&quot;slidesToShow&quot;:1,&quot;appendDots&quot;:&quot;#dots-6a03d287abf7c&quot;,&quot;prevArrow&quot;:&quot;&lt;button type=\\&quot;button\\&quot; class=\\&quot;btn btn-primary slick-prev\\&quot;&gt;&lt;svg class=\\&quot;svg-chevron-left-dims\\&quot;&gt;&lt;use xlink:href=&#039;https:\\\/\\\/gobierno.udd.cl\\\/dccs\\\/wp-content\\\/themes\\\/facultades-2018\\\/assets\\\/img\\\/svg\\\/dist\\\/main.svg?version=1695853099#chevron-left&#039;&gt;&lt;\\\/use&gt;&lt;\\\/svg&gt;&lt;span class=\\&quot;sr-only\\&quot;&gt;Anterior&lt;\\\/span&gt;&lt;\\\/button&gt;&quot;,&quot;nextArrow&quot;:&quot;&lt;button type=\\&quot;button\\&quot; class=\\&quot;btn btn-primary slick-next\\&quot;&gt;&lt;svg class=\\&quot;svg-chevron-right-dims\\&quot;&gt;&lt;use xlink:href=&#039;https:\\\/\\\/gobierno.udd.cl\\\/dccs\\\/wp-content\\\/themes\\\/facultades-2018\\\/assets\\\/img\\\/svg\\\/dist\\\/main.svg?version=1695853099#chevron-right&#039;&gt;&lt;\\\/use&gt;&lt;\\\/svg&gt;&lt;span class=\\&quot;sr-only\\&quot;&gt;Siguiente&lt;\\\/span&gt;&lt;\\\/button&gt;&quot;,&quot;infinite&quot;:true,&quot;dots&quot;:true}'\n\t\t>\n\t\t\t\t\t\t\t<figure>\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"720\" src=\"https:\/\/gobierno.udd.cl\/dccs\/wp-content\/plugins\/wp-async-img-load\/blank.png\" class=\"attachment-1280x720 size-1280x720 lazyload\" alt=\"\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" data-src=\"https:\/\/gobierno.udd.cl\/dccs\/files\/2025\/08\/2407_02-1-1366x768.jpg\" data-srcset=\"https:\/\/gobierno.udd.cl\/dccs\/files\/2025\/08\/2407_02-1-1366x768.jpg 1366w, https:\/\/gobierno.udd.cl\/dccs\/files\/2025\/08\/2407_02-1-1920x1080.jpg 1920w, https:\/\/gobierno.udd.cl\/dccs\/files\/2025\/08\/2407_02-1-680x382.jpg 680w\" \/>\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t<figure>\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"720\" src=\"https:\/\/gobierno.udd.cl\/dccs\/wp-content\/plugins\/wp-async-img-load\/blank.png\" class=\"attachment-1280x720 size-1280x720 lazyload\" alt=\"\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" data-src=\"https:\/\/gobierno.udd.cl\/dccs\/files\/2025\/08\/2407_01-1366x768.jpg\" data-srcset=\"https:\/\/gobierno.udd.cl\/dccs\/files\/2025\/08\/2407_01-1366x768.jpg 1366w, https:\/\/gobierno.udd.cl\/dccs\/files\/2025\/08\/2407_01-1920x1080.jpg 1920w, https:\/\/gobierno.udd.cl\/dccs\/files\/2025\/08\/2407_01-680x382.jpg 680w\" \/>\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t<div\n\t\t\tclass=\"carousel-gallery--carousel-dots\"\n\t\t\tid=\"dots-6a03d287abf7c\"\n\t\t><\/div>\n\t<\/div>\n<\/section>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con este nuevo graduado, el programa de la Facultad de Gobierno UDD suma un total de 24 doctores que han recibido el grado desde su creaci\u00f3n. V\u00edctor M\u00e1rquez defendi\u00f3 con \u00e9xito su tesis titulada \u201cComplex Oscillatory Dynamics in Neural Populations Using Map-Based Models\u201d, obteniendo el grado de Doctor en Ciencias de la Complejidad Social, otorgado [&hellip;]<\/p>\n","protected":false},"author":9192240,"featured_media":4679,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[107],"tags":[],"class_list":["post-4678","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Doctorado en Ciencias de la Complejidad Social suma nuevo graduado con tesis sobre oscilaciones cerebrales complejas - Doctorado en Ciencias de la Complejidad Social<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gobierno.udd.cl\/dccs\/2025\/08\/04\/doctorado-en-ciencias-de-la-complejidad-social-suma-nuevo-graduado-con-tesis-sobre-oscilaciones-cerebrales-complejas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Doctorado en Ciencias de la Complejidad Social suma nuevo graduado con tesis sobre oscilaciones cerebrales complejas - Doctorado en Ciencias de la Complejidad Social\" \/>\n<meta property=\"og:description\" content=\"Con este nuevo graduado, el programa de la Facultad de Gobierno UDD suma un total de 24 doctores que han recibido el grado desde su creaci\u00f3n. V\u00edctor M\u00e1rquez defendi\u00f3 con \u00e9xito su tesis titulada \u201cComplex Oscillatory Dynamics in Neural Populations Using Map-Based Models\u201d, obteniendo el grado de Doctor en Ciencias de la Complejidad Social, otorgado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gobierno.udd.cl\/dccs\/2025\/08\/04\/doctorado-en-ciencias-de-la-complejidad-social-suma-nuevo-graduado-con-tesis-sobre-oscilaciones-cerebrales-complejas\/\" \/>\n<meta property=\"og:site_name\" content=\"Doctorado en Ciencias de la Complejidad Social\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-04T14:52:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-05T14:53:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gobierno.udd.cl\/dccs\/files\/2025\/08\/2407_02-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"claudiagodia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"claudiagodia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/gobierno.udd.cl\/dccs\/2025\/08\/04\/doctorado-en-ciencias-de-la-complejidad-social-suma-nuevo-graduado-con-tesis-sobre-oscilaciones-cerebrales-complejas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/gobierno.udd.cl\/dccs\/2025\/08\/04\/doctorado-en-ciencias-de-la-complejidad-social-suma-nuevo-graduado-con-tesis-sobre-oscilaciones-cerebrales-complejas\/\"},\"author\":{\"name\":\"claudiagodia\",\"@id\":\"https:\/\/gobierno.udd.cl\/dccs\/#\/schema\/person\/a34b5db7e59307019967393aeeca7130\"},\"headline\":\"Doctorado en Ciencias de la Complejidad Social suma nuevo graduado con tesis sobre oscilaciones cerebrales complejas\",\"datePublished\":\"2025-08-04T14:52:09+00:00\",\"dateModified\":\"2025-08-05T14:53:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/gobierno.udd.cl\/dccs\/2025\/08\/04\/doctorado-en-ciencias-de-la-complejidad-social-suma-nuevo-graduado-con-tesis-sobre-oscilaciones-cerebrales-complejas\/\"},\"wordCount\":282,\"image\":{\"@id\":\"https:\/\/gobierno.udd.cl\/dccs\/2025\/08\/04\/doctorado-en-ciencias-de-la-complejidad-social-suma-nuevo-graduado-con-tesis-sobre-oscilaciones-cerebrales-complejas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/gobierno.udd.cl\/dccs\/files\/2025\/08\/2407_02-1-scaled.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/gobierno.udd.cl\/dccs\/2025\/08\/04\/doctorado-en-ciencias-de-la-complejidad-social-suma-nuevo-graduado-con-tesis-sobre-oscilaciones-cerebrales-complejas\/\",\"url\":\"https:\/\/gobierno.udd.cl\/dccs\/2025\/08\/04\/doctorado-en-ciencias-de-la-complejidad-social-suma-nuevo-graduado-con-tesis-sobre-oscilaciones-cerebrales-complejas\/\",\"name\":\"Doctorado en Ciencias de la Complejidad Social suma nuevo graduado con tesis sobre oscilaciones cerebrales complejas - Doctorado en Ciencias de la Complejidad Social\",\"isPartOf\":{\"@id\":\"https:\/\/gobierno.udd.cl\/dccs\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/gobierno.udd.cl\/dccs\/2025\/08\/04\/doctorado-en-ciencias-de-la-complejidad-social-suma-nuevo-graduado-con-tesis-sobre-oscilaciones-cerebrales-complejas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/gobierno.udd.cl\/dccs\/2025\/08\/04\/doctorado-en-ciencias-de-la-complejidad-social-suma-nuevo-graduado-con-tesis-sobre-oscilaciones-cerebrales-complejas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/gobierno.udd.cl\/dccs\/files\/2025\/08\/2407_02-1-scaled.jpg\",\"datePublished\":\"2025-08-04T14:52:09+00:00\",\"dateModified\":\"2025-08-05T14:53:00+00:00\",\"author\":{\"@id\":\"https:\/\/gobierno.udd.cl\/dccs\/#\/schema\/person\/a34b5db7e59307019967393aeeca7130\"},\"breadcrumb\":{\"@id\":\"https:\/\/gobierno.udd.cl\/dccs\/2025\/08\/04\/doctorado-en-ciencias-de-la-complejidad-social-suma-nuevo-graduado-con-tesis-sobre-oscilaciones-cerebrales-complejas\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/gobierno.udd.cl\/dccs\/2025\/08\/04\/doctorado-en-ciencias-de-la-complejidad-social-suma-nuevo-graduado-con-tesis-sobre-oscilaciones-cerebrales-complejas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/gobierno.udd.cl\/dccs\/2025\/08\/04\/doctorado-en-ciencias-de-la-complejidad-social-suma-nuevo-graduado-con-tesis-sobre-oscilaciones-cerebrales-complejas\/#primaryimage\",\"url\":\"https:\/\/gobierno.udd.cl\/dccs\/files\/2025\/08\/2407_02-1-scaled.jpg\",\"contentUrl\":\"https:\/\/gobierno.udd.cl\/dccs\/files\/2025\/08\/2407_02-1-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/gobierno.udd.cl\/dccs\/2025\/08\/04\/doctorado-en-ciencias-de-la-complejidad-social-suma-nuevo-graduado-con-tesis-sobre-oscilaciones-cerebrales-complejas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/gobierno.udd.cl\/dccs\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Doctorado en Ciencias de la Complejidad Social suma nuevo graduado con tesis sobre oscilaciones cerebrales complejas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/gobierno.udd.cl\/dccs\/#website\",\"url\":\"https:\/\/gobierno.udd.cl\/dccs\/\",\"name\":\"Doctorado en Ciencias de la Complejidad Social\",\"description\":\"Centro de Investigaci\u00f3n en Complejidad Social | UDD\",\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/gobierno.udd.cl\/dccs\/#\/schema\/person\/a34b5db7e59307019967393aeeca7130\",\"name\":\"claudiagodia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/gobierno.udd.cl\/dccs\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7c585f20c9cd5b1fc8956abfd060f1af449288eb4e630466a5a53a84641a9ca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7c585f20c9cd5b1fc8956abfd060f1af449288eb4e630466a5a53a84641a9ca?s=96&d=mm&r=g\",\"caption\":\"claudiagodia\"},\"url\":\"https:\/\/gobierno.udd.cl\/dccs\/author\/claudiagodia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Doctorado en Ciencias de la Complejidad Social suma nuevo graduado con tesis sobre oscilaciones cerebrales complejas - Doctorado en Ciencias de la Complejidad Social","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gobierno.udd.cl\/dccs\/2025\/08\/04\/doctorado-en-ciencias-de-la-complejidad-social-suma-nuevo-graduado-con-tesis-sobre-oscilaciones-cerebrales-complejas\/","og_locale":"es_ES","og_type":"article","og_title":"Doctorado en Ciencias de la Complejidad Social suma nuevo graduado con tesis sobre oscilaciones cerebrales complejas - Doctorado en Ciencias de la Complejidad Social","og_description":"Con este nuevo graduado, el programa de la Facultad de Gobierno UDD suma un total de 24 doctores que han recibido el grado desde su creaci\u00f3n. V\u00edctor M\u00e1rquez defendi\u00f3 con \u00e9xito su tesis titulada \u201cComplex Oscillatory Dynamics in Neural Populations Using Map-Based Models\u201d, obteniendo el grado de Doctor en Ciencias de la Complejidad Social, otorgado [&hellip;]","og_url":"https:\/\/gobierno.udd.cl\/dccs\/2025\/08\/04\/doctorado-en-ciencias-de-la-complejidad-social-suma-nuevo-graduado-con-tesis-sobre-oscilaciones-cerebrales-complejas\/","og_site_name":"Doctorado en Ciencias de la Complejidad Social","article_published_time":"2025-08-04T14:52:09+00:00","article_modified_time":"2025-08-05T14:53:00+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/gobierno.udd.cl\/dccs\/files\/2025\/08\/2407_02-1-scaled.jpg","type":"image\/jpeg"}],"author":"claudiagodia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"claudiagodia","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gobierno.udd.cl\/dccs\/2025\/08\/04\/doctorado-en-ciencias-de-la-complejidad-social-suma-nuevo-graduado-con-tesis-sobre-oscilaciones-cerebrales-complejas\/#article","isPartOf":{"@id":"https:\/\/gobierno.udd.cl\/dccs\/2025\/08\/04\/doctorado-en-ciencias-de-la-complejidad-social-suma-nuevo-graduado-con-tesis-sobre-oscilaciones-cerebrales-complejas\/"},"author":{"name":"claudiagodia","@id":"https:\/\/gobierno.udd.cl\/dccs\/#\/schema\/person\/a34b5db7e59307019967393aeeca7130"},"headline":"Doctorado en Ciencias de la Complejidad Social suma nuevo graduado con tesis sobre oscilaciones cerebrales complejas","datePublished":"2025-08-04T14:52:09+00:00","dateModified":"2025-08-05T14:53:00+00:00","mainEntityOfPage":{"@id":"https:\/\/gobierno.udd.cl\/dccs\/2025\/08\/04\/doctorado-en-ciencias-de-la-complejidad-social-suma-nuevo-graduado-con-tesis-sobre-oscilaciones-cerebrales-complejas\/"},"wordCount":282,"image":{"@id":"https:\/\/gobierno.udd.cl\/dccs\/2025\/08\/04\/doctorado-en-ciencias-de-la-complejidad-social-suma-nuevo-graduado-con-tesis-sobre-oscilaciones-cerebrales-complejas\/#primaryimage"},"thumbnailUrl":"https:\/\/gobierno.udd.cl\/dccs\/files\/2025\/08\/2407_02-1-scaled.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gobierno.udd.cl\/dccs\/2025\/08\/04\/doctorado-en-ciencias-de-la-complejidad-social-suma-nuevo-graduado-con-tesis-sobre-oscilaciones-cerebrales-complejas\/","url":"https:\/\/gobierno.udd.cl\/dccs\/2025\/08\/04\/doctorado-en-ciencias-de-la-complejidad-social-suma-nuevo-graduado-con-tesis-sobre-oscilaciones-cerebrales-complejas\/","name":"Doctorado en Ciencias de la Complejidad Social suma nuevo graduado con tesis sobre oscilaciones cerebrales complejas - Doctorado en Ciencias de la Complejidad Social","isPartOf":{"@id":"https:\/\/gobierno.udd.cl\/dccs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gobierno.udd.cl\/dccs\/2025\/08\/04\/doctorado-en-ciencias-de-la-complejidad-social-suma-nuevo-graduado-con-tesis-sobre-oscilaciones-cerebrales-complejas\/#primaryimage"},"image":{"@id":"https:\/\/gobierno.udd.cl\/dccs\/2025\/08\/04\/doctorado-en-ciencias-de-la-complejidad-social-suma-nuevo-graduado-con-tesis-sobre-oscilaciones-cerebrales-complejas\/#primaryimage"},"thumbnailUrl":"https:\/\/gobierno.udd.cl\/dccs\/files\/2025\/08\/2407_02-1-scaled.jpg","datePublished":"2025-08-04T14:52:09+00:00","dateModified":"2025-08-05T14:53:00+00:00","author":{"@id":"https:\/\/gobierno.udd.cl\/dccs\/#\/schema\/person\/a34b5db7e59307019967393aeeca7130"},"breadcrumb":{"@id":"https:\/\/gobierno.udd.cl\/dccs\/2025\/08\/04\/doctorado-en-ciencias-de-la-complejidad-social-suma-nuevo-graduado-con-tesis-sobre-oscilaciones-cerebrales-complejas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gobierno.udd.cl\/dccs\/2025\/08\/04\/doctorado-en-ciencias-de-la-complejidad-social-suma-nuevo-graduado-con-tesis-sobre-oscilaciones-cerebrales-complejas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gobierno.udd.cl\/dccs\/2025\/08\/04\/doctorado-en-ciencias-de-la-complejidad-social-suma-nuevo-graduado-con-tesis-sobre-oscilaciones-cerebrales-complejas\/#primaryimage","url":"https:\/\/gobierno.udd.cl\/dccs\/files\/2025\/08\/2407_02-1-scaled.jpg","contentUrl":"https:\/\/gobierno.udd.cl\/dccs\/files\/2025\/08\/2407_02-1-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/gobierno.udd.cl\/dccs\/2025\/08\/04\/doctorado-en-ciencias-de-la-complejidad-social-suma-nuevo-graduado-con-tesis-sobre-oscilaciones-cerebrales-complejas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/gobierno.udd.cl\/dccs\/"},{"@type":"ListItem","position":2,"name":"Doctorado en Ciencias de la Complejidad Social suma nuevo graduado con tesis sobre oscilaciones cerebrales complejas"}]},{"@type":"WebSite","@id":"https:\/\/gobierno.udd.cl\/dccs\/#website","url":"https:\/\/gobierno.udd.cl\/dccs\/","name":"Doctorado en Ciencias de la Complejidad Social","description":"Centro de Investigaci\u00f3n en Complejidad Social | UDD","inLanguage":"es"},{"@type":"Person","@id":"https:\/\/gobierno.udd.cl\/dccs\/#\/schema\/person\/a34b5db7e59307019967393aeeca7130","name":"claudiagodia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gobierno.udd.cl\/dccs\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7c585f20c9cd5b1fc8956abfd060f1af449288eb4e630466a5a53a84641a9ca?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7c585f20c9cd5b1fc8956abfd060f1af449288eb4e630466a5a53a84641a9ca?s=96&d=mm&r=g","caption":"claudiagodia"},"url":"https:\/\/gobierno.udd.cl\/dccs\/author\/claudiagodia\/"}]}},"featured_image_url":"https:\/\/gobierno.udd.cl\/dccs\/files\/2025\/08\/2407_02-1-scaled.jpg","_links":{"self":[{"href":"https:\/\/gobierno.udd.cl\/dccs\/wp-json\/wp\/v2\/posts\/4678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gobierno.udd.cl\/dccs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gobierno.udd.cl\/dccs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gobierno.udd.cl\/dccs\/wp-json\/wp\/v2\/users\/9192240"}],"replies":[{"embeddable":true,"href":"https:\/\/gobierno.udd.cl\/dccs\/wp-json\/wp\/v2\/comments?post=4678"}],"version-history":[{"count":1,"href":"https:\/\/gobierno.udd.cl\/dccs\/wp-json\/wp\/v2\/posts\/4678\/revisions"}],"predecessor-version":[{"id":4681,"href":"https:\/\/gobierno.udd.cl\/dccs\/wp-json\/wp\/v2\/posts\/4678\/revisions\/4681"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gobierno.udd.cl\/dccs\/wp-json\/wp\/v2\/media\/4679"}],"wp:attachment":[{"href":"https:\/\/gobierno.udd.cl\/dccs\/wp-json\/wp\/v2\/media?parent=4678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gobierno.udd.cl\/dccs\/wp-json\/wp\/v2\/categories?post=4678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gobierno.udd.cl\/dccs\/wp-json\/wp\/v2\/tags?post=4678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}